{"id":4075,"date":"2020-06-13T09:28:00","date_gmt":"2020-06-13T09:28:00","guid":{"rendered":"https:\/\/www.passportscan.net\/non-classifiee\/passportscan-ltd-obtient-une-integration-validee-par-oracle-avec-oracle-hospitality\/"},"modified":"2024-06-10T11:12:40","modified_gmt":"2024-06-10T11:12:40","slug":"passportscan-ltd-obtient-une-integration-validee-par-oracle-avec-oracle-hospitality","status":"publish","type":"post","link":"https:\/\/www.passportscan.net\/fr\/passportscan-ltd-obtient-une-integration-validee-par-oracle-avec-oracle-hospitality\/","title":{"rendered":"PASSPORTSCAN LTD obtient une int\u00e9gration valid\u00e9e par Oracle avec Oracle Hospitality"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Cette int\u00e9gration permet une synchronisation automatique entre PassportScan et Oracle Hospitality Suite8, am\u00e9liorant l&rsquo;exp\u00e9rience client avec un \u00e9change de donn\u00e9es simplifi\u00e9.<\/h2>\n\n<p><\/p>\n\n<p>PASSPORTSCAN LTD, membre de niveau Gold du r\u00e9seau de partenaires Oracle (OPN), a annonc\u00e9 aujourd&rsquo;hui avoir obtenu l&rsquo;int\u00e9gration valid\u00e9e par Oracle de PassportScan avec Oracle Hospitality Suite8. Avec cette int\u00e9gration valid\u00e9e, PassportScan capture et g\u00e8re les donn\u00e9es des cartes d&rsquo;identit\u00e9 et des passeports, puis envoie imm\u00e9diatement les donn\u00e9es \u00e0 Oracle Hospitality Suite8. Cet \u00e9change de donn\u00e9es en temps r\u00e9el r\u00e9duit les erreurs humaines et acc\u00e9l\u00e8re le processus d&rsquo;enregistrement. \u00abL&rsquo;obtention de l&rsquo;int\u00e9gration valid\u00e9e par Oracle donne aux clients l&rsquo;assurance que l&rsquo;int\u00e9gration de PassportScan avec Oracle Hospitality Suite8 est fonctionnellement solide et fonctionne comme test\u00e9 \u00bb, a d\u00e9clar\u00e9 David Hicks, vice-pr\u00e9sident du d\u00e9veloppement commercial cloud ISV mondial chez Oracle. \u00ab Pour les solutions d\u00e9ploy\u00e9es sur site, dans le cloud, ou les deux, l&rsquo;int\u00e9gration valid\u00e9e par Oracle est soumise \u00e0 un processus d&rsquo;examen technique rigoureux et de test qui aide \u00e0 r\u00e9duire les risques de d\u00e9ploiement et am\u00e9liore l&rsquo;exp\u00e9rience utilisateur de l&rsquo;offre int\u00e9gr\u00e9e du partenaire.\u00bb<\/p>\n\n<p>PassportScan simplifie la collecte et la gestion des donn\u00e9es d&rsquo;identification des clients. Dans l&rsquo;interface PassportScan, les collaborateurs peuvent traiter les donn\u00e9es des nouveaux clients et des clients r\u00e9guliers, ajouter des compagnons \u00e0 la r\u00e9servation, capturer la signature du client et d&rsquo;autres donn\u00e9es utiles telles que les adresses e-mail, les num\u00e9ros de t\u00e9l\u00e9phone et les pr\u00e9f\u00e9rences en mati\u00e8re de confidentialit\u00e9. De plus, en cliquant simplement sur le bouton PassportScan, l&rsquo;int\u00e9gration permet de r\u00e9cup\u00e9rer des donn\u00e9es telles que les heures d&rsquo;arriv\u00e9e et de d\u00e9part, le type de chambre et le tarif de la chambre \u00e0 partir d&rsquo;Oracle Hospitality Suite8. De plus, une fois que l&rsquo;ID du client est scann\u00e9, les donn\u00e9es sont synchronis\u00e9es avec les profils des clients dans Oracle Hospitality Suite8. L&rsquo;int\u00e9gration se traduit par une exp\u00e9rience client am\u00e9lior\u00e9e en r\u00e9duisant les temps d&rsquo;attente et les files d&rsquo;attente, tout en respectant pleinement la conformit\u00e9 au RGPD et les normes de s\u00e9curit\u00e9.<\/p>\n\n<p>\u00c0 propos de l&rsquo;int\u00e9gration valid\u00e9e par Oracle L&rsquo;int\u00e9gration valid\u00e9e par Oracle, disponible via le r\u00e9seau de partenaires Oracle (OPN), donne aux clients l&rsquo;assurance que l&rsquo;int\u00e9gration d&rsquo;un produit logiciel partenaire compl\u00e9mentaire avec une application Oracle \u00ab\u00a0sur site\u00a0\u00bb ainsi que bas\u00e9e sur le cloud a \u00e9t\u00e9 valid\u00e9e et que les produits fonctionnent ensemble comme pr\u00e9vu. Cela peut aider les clients \u00e0 r\u00e9duire les risques, \u00e0 am\u00e9liorer les cycles de mise en \u0153uvre du syst\u00e8me et \u00e0 simplifier les mises \u00e0 niveau et la maintenance. L&rsquo;int\u00e9gration valid\u00e9e par Oracle applique un processus technique rigoureux pour examiner les int\u00e9grations partenaires et les partenaires qui r\u00e9ussissent \u00e0 compl\u00e9ter le programme sont autoris\u00e9s \u00e0 utiliser le logo \u00ab\u00a0Oracle Validated Integration\u00a0\u00bb. Pour plus d&rsquo;informations, veuillez visiter Oracle.com \u00e0 propos de l&rsquo;int\u00e9gration valid\u00e9e par Oracle.&#13;\n&#13;\n\u00c0 propos d&rsquo;Oracle PartnerNetwork Oracle PartnerNetwork (OPN) Specialized est la derni\u00e8re version du programme de partenariat d&rsquo;Oracle qui fournit aux partenaires des outils pour mieux d\u00e9velopper, vendre et mettre en \u0153uvre les solutions Oracle. OPN Specialized offre des ressources pour former et soutenir les connaissances sp\u00e9cialis\u00e9es des produits et solutions Oracle et a \u00e9volu\u00e9 pour reconna\u00eetre le portefeuille de produits en expansion d&rsquo;Oracle, la base de partenaires et les opportunit\u00e9s commerciales. La cl\u00e9 des derni\u00e8res am\u00e9liorations apport\u00e9es \u00e0 OPN est la capacit\u00e9 pour les partenaires de se diff\u00e9rencier gr\u00e2ce aux sp\u00e9cialisations. Les sp\u00e9cialisations sont obtenues gr\u00e2ce au d\u00e9veloppement de comp\u00e9tences, aux r\u00e9sultats commerciaux, \u00e0 l&rsquo;expertise et aux succ\u00e8s av\u00e9r\u00e9s.<\/p>\n\n<p>Pour en savoir plus, visitez <a href=\"http:\/\/www.oracle.com\/partners.\" target=\"_blank\" rel=\"noopener\">http:\/\/www.oracle.com\/partners.<\/a> <strong>Marques d\u00e9pos\u00e9es<\/strong> Oracle et Java sont des marques d\u00e9pos\u00e9es d&rsquo;Oracle et\/ou de ses soci\u00e9t\u00e9s affili\u00e9es. <strong>\u00c0 propos de PassportScan PassportScan<\/strong> est une soci\u00e9t\u00e9 de premier plan avec plus de 15 ans d&rsquo;exp\u00e9rience, qui propose des solutions qui simplifient la collecte et la gestion des donn\u00e9es d&rsquo;identification des clients, en r\u00e9solvant les d\u00e9fis rencontr\u00e9s dans la capture, le stockage et le transfert des donn\u00e9es des clients de mani\u00e8re simple, rapide et organis\u00e9e. Notre mission est d&rsquo;aider les entreprises de toutes tailles \u00e0 am\u00e9liorer leur processus d&rsquo;enregistrement et \u00e0 conserver les informations personnelles de mani\u00e8re s\u00e9curis\u00e9e. L&rsquo;un de nos plus grands centres d&rsquo;int\u00e9r\u00eat, traitant des donn\u00e9es personnelles, a toujours \u00e9t\u00e9 la s\u00e9curit\u00e9. Le choix, apr\u00e8s avoir mis \u00e0 jour notre logiciel pour une conformit\u00e9 totale au RGPD, a \u00e9t\u00e9 de passer PassportScan \u00e0 une plateforme Cloud. Les flux de travail sont rationalis\u00e9s et de bonnes pratiques de gestion de la confidentialit\u00e9 sont garanties. Nos solutions flexibles peuvent r\u00e9pondre aux exigences des clients et des r\u00e9glementations les plus exigeants.<\/p>\n\n<p>Notre vision est d&rsquo;aider les clients et les entreprises \u00e0 relever les d\u00e9fis auxquels ils sont confront\u00e9s lors de l&rsquo;\u00e9change de donn\u00e9es personnelles. Nous nous effor\u00e7ons de cr\u00e9er une norme commune pour des interactions fluides entre les deux parties, offrant aux clients de tous les secteurs un contr\u00f4le direct sur leurs propres donn\u00e9es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette int\u00e9gration permet une synchronisation automatique entre PassportScan et Oracle Hospitality Suite8, am\u00e9liorant l&rsquo;exp\u00e9rience client avec un \u00e9change de donn\u00e9es simplifi\u00e9. PASSPORTSCAN LTD, membre de niveau Gold du r\u00e9seau de partenaires Oracle (OPN), a annonc\u00e9 aujourd&rsquo;hui avoir obtenu l&rsquo;int\u00e9gration valid\u00e9e par Oracle de PassportScan avec Oracle Hospitality Suite8. Avec cette int\u00e9gration valid\u00e9e, PassportScan capture et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2450,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-4075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.passportscan.net\/fr\/wp-json\/wp\/v2\/posts\/4075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.passportscan.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.passportscan.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.passportscan.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.passportscan.net\/fr\/wp-json\/wp\/v2\/comments?post=4075"}],"version-history":[{"count":1,"href":"https:\/\/www.passportscan.net\/fr\/wp-json\/wp\/v2\/posts\/4075\/revisions"}],"predecessor-version":[{"id":4076,"href":"https:\/\/www.passportscan.net\/fr\/wp-json\/wp\/v2\/posts\/4075\/revisions\/4076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.passportscan.net\/fr\/wp-json\/wp\/v2\/media\/2450"}],"wp:attachment":[{"href":"https:\/\/www.passportscan.net\/fr\/wp-json\/wp\/v2\/media?parent=4075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.passportscan.net\/fr\/wp-json\/wp\/v2\/categories?post=4075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.passportscan.net\/fr\/wp-json\/wp\/v2\/tags?post=4075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}